{"id":5884,"date":"2014-02-04T10:49:25","date_gmt":"2014-02-04T10:49:25","guid":{"rendered":"http:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0.jpg"},"modified":"2014-02-04T10:49:25","modified_gmt":"2014-02-04T10:49:25","slug":"antz0","status":"inherit","type":"attachment","link":"https:\/\/www.eyeplug.net\/magazine\/a-n-t-z-by-johna-johnson\/antz0\/","title":{"rendered":"antz0"},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-5884","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0.jpg' rel=\"lightbox[5884]\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAYYAAADcAQMAAABOLJSDAAAAA1BMVEUAAACnej3aAAAAAXRSTlMAQObYZgAAACJJREFUaIHtwTEBAAAAwqD1T20ND6AAAAAAAAAAAAAA4N8AKvgAAUFIrrEAAAAASUVORK5CYII=\" class=\"attachment-medium size-medium lazy-img\" alt=\"\" srcset=\"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0-300x200.jpg 300w, https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0-300x200.jpg\" loading=\"lazy\" data-wp-pid=\"5884\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":400,"file":"2014\/02\/antz0.jpg","sizes":{"woocommerce_thumbnail":{"file":"antz0-300x200.jpg","width":300,"height":200,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0-300x200.jpg"},"woocommerce_gallery_thumbnail":{"file":"antz0-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0-100x100.jpg"},"thumbnail":{"file":"antz0-150x150.jpg","width":150,"height":150,"ewww_image_optimizer":"Reduced by 7.9% (1,006.0&nbsp;B) - Previously Optimized","mime_type":"image\/jpeg","source_url":"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0-150x150.jpg"},"medium":{"file":"antz0-300x200.jpg","width":300,"height":200,"ewww_image_optimizer":"Reduced by 7.1% (2.0&nbsp;kB) - Previously Optimized","mime_type":"image\/jpeg","source_url":"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0-300x200.jpg"},"full":{"file":"antz0.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5880,"source_url":"https:\/\/www.eyeplug.net\/magazine\/wp-content\/uploads\/2014\/02\/antz0.jpg","_links":{"self":[{"href":"https:\/\/www.eyeplug.net\/magazine\/wp-json\/wp\/v2\/media\/5884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eyeplug.net\/magazine\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.eyeplug.net\/magazine\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.eyeplug.net\/magazine\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eyeplug.net\/magazine\/wp-json\/wp\/v2\/comments?post=5884"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5880,"href":"https:\/\/www.eyeplug.net\/magazine\/wp-json\/wp\/v2\/posts\/5880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}